{"id":959,"date":"2024-05-13T15:02:43","date_gmt":"2024-05-13T07:02:43","guid":{"rendered":"https:\/\/tzfoodmachine.com\/?p=959"},"modified":"2024-05-21T17:25:58","modified_gmt":"2024-05-21T09:25:58","slug":"commercial-onion-dicer-machine","status":"publish","type":"post","link":"https:\/\/tzfoodmachine.com\/pt\/commercial-onion-dicer-machine\/","title":{"rendered":"M\u00e1quina comercial de cortar cebola"},"content":{"rendered":"<p>A m\u00e1quina cortadora de cebola \u00e9 usada em cozinhas comerciais e ind\u00fastrias de processamento de alimentos para cortar cebolas de forma r\u00e1pida e eficiente. Esta m\u00e1quina pode cortar at\u00e9 1.000 kg de cebolas em cubos por hora. Voc\u00ea pode ajustar o tamanho da cebola picada conforme sua necessidade. A m\u00e1quina de cortar cebola Taizy pode cortar cebolas em dados de 3 mm, 4 mm, 5 mm, 6 mm, 7 mm, 8 mm, 9 mm, 10 mm, 12 mm, 15 mm e 20 mm. Al\u00e9m disso, este vers\u00e1til cortador de cebola tamb\u00e9m pode cortar rodelas e rodelas de cebola.<\/p>    <figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\"> <iframe loading=\"lazy\" title=\"M\u00e1quina de cortar vegetais em a\u00e7\u00e3o | M\u00e1quina de cortar cebola | Cebola, batata e muito mais!\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/yoeBUc9HcjQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe> <\/div><figcaption class=\"wp-element-caption\">v\u00eddeo de m\u00e1quina comercial de cortar vegetais<\/figcaption><\/figure>    <h2 class=\"wp-block-heading\">Vantagens da m\u00e1quina de cortar cebola Taizy<\/h2>    <ol class=\"wp-block-list\"> <li>Voc\u00ea tamb\u00e9m pode usar esta m\u00e1quina para cortar batatas, <a href=\"https:\/\/en.wikipedia.org\/wiki\/Carrot\" rel=\"nofollow noopener\" target=\"_blank\">cenoura<\/a>s, tomates, ma\u00e7\u00e3s e muitos outros vegetais e frutas.<\/li>    <li>A m\u00e1quina \u00e9 feita de a\u00e7o inoxid\u00e1vel, que \u00e9 resistente e dur\u00e1vel.<\/li>    <li>A ampla abertura de alimenta\u00e7\u00e3o \u00e9 mais segura.<\/li>    <li>A m\u00e1quina cortadora de cebola pode cortar mais de 10 tamanhos de cebola em cubos.<\/li>    <li>A cebola cortada em cubos por esta m\u00e1quina tem uma superf\u00edcie de corte lisa e uma alta taxa de moldagem.<\/li>    <li>A m\u00e1quina cortadora de cebola est\u00e1 equipada com um cortador de fatiar, um cortador de ralar e um cortador de cubos. Voc\u00ea pode obter fatias de cebola, tiras de cebola e cebolas em cubos trocando as facas.<\/li> <\/ol>    <figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"> <figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"720\" data-id=\"966\" src=\"https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/feed-port.webp\" alt=\"porta de alimenta\u00e7\u00e3o\" class=\"wp-image-966\" srcset=\"https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/feed-port.webp 540w, https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/feed-port-270x360.webp 270w, https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/feed-port-9x12.webp 9w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><figcaption class=\"wp-element-caption\">porta de alimenta\u00e7\u00e3o<\/figcaption><\/figure>    <figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"720\" data-id=\"968\" src=\"https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/onion-cube-dicer-machine.webp\" alt=\"m\u00e1quina de cortar cubos de cebola\" class=\"wp-image-968\" srcset=\"https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/onion-cube-dicer-machine.webp 540w, https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/onion-cube-dicer-machine-270x360.webp 270w, https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/onion-cube-dicer-machine-9x12.webp 9w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><figcaption class=\"wp-element-caption\">m\u00e1quina de cortar cubos de cebola<\/figcaption><\/figure> <\/figure>    <h2 class=\"wp-block-heading\">Que outros materiais a m\u00e1quina cortadora de cebola pode cortar?<\/h2>    <p>Al\u00e9m de cebolas, esta m\u00e1quina tamb\u00e9m pode cortar tomates, batatas, cenouras, ab\u00f3bora, repolho, gengibre, peras, ma\u00e7\u00e3s, kiwis, brotos de bambu, inhame, abacaxi, mam\u00e3o, piment\u00e3o verde e muitas outras frutas e vegetais.<\/p>    <p class=\"translation-block\">\u00c9 importante notar que se quiser obter cebolas cortadas em cubos de alta qualidade, precisa de usar uma <a href=\"https:\/\/tzfoodmachine.com\/pt\/onion-peeling-machine\/\">descascadora de cebolas<\/a> e uma <a href=\"https:\/\/tzfoodmachine.com\/pt\/onion-root-cutting-machine\/\">m\u00e1quina de corte de raiz de cebola<\/a> para processar as cebolas.<\/p>    <p>Ali\u00e1s, o di\u00e2metro m\u00e1ximo de corte do material n\u00e3o deve ser superior a 80mm, se for maior que esse di\u00e2metro deve ser previamente cortado em pequenos peda\u00e7os.<\/p>    <figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\"> <figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" data-id=\"576\" src=\"https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/04\/clean-potato.webp\" alt=\"batata limpa\" class=\"wp-image-576\" srcset=\"https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/04\/clean-potato.webp 720w, https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/04\/clean-potato-480x360.webp 480w, https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/04\/clean-potato-150x113.webp 150w, https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/04\/clean-potato-16x12.webp 16w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">batata limpa<\/figcaption><\/figure>    <figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" data-id=\"590\" src=\"https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/04\/tomato.webp\" alt=\"tomate\" class=\"wp-image-590\" srcset=\"https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/04\/tomato.webp 720w, https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/04\/tomato-480x360.webp 480w, https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/04\/tomato-150x113.webp 150w, https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/04\/tomato-16x12.webp 16w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">tomate<\/figcaption><\/figure>    <figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" data-id=\"675\" src=\"https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/04\/carrot-1.webp\" alt=\"cenoura\" class=\"wp-image-675\" srcset=\"https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/04\/carrot-1.webp 720w, https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/04\/carrot-1-480x360.webp 480w, https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/04\/carrot-1-150x113.webp 150w, https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/04\/carrot-1-16x12.webp 16w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">cenoura<\/figcaption><\/figure> <\/figure>    <h2 class=\"wp-block-heading\">Par\u00e2metros da m\u00e1quina comercial de corte de cebola<\/h2>    <figure class=\"wp-block-table\"><table><tbody><tr><td>Capacidade<\/td><td>1000kg\/hora<\/td><\/tr><tr><td>Poder<\/td><td>0,75 kW<\/td><\/tr><tr><td>Tens\u00e3o<\/td><td>220v\/380v<\/td><\/tr><tr><td>Peso<\/td><td>100kg<\/td><\/tr><tr><td>Tamanho<\/td><td>560x600x1310mm<\/td><\/tr><\/tbody><\/table><figcaption class=\"wp-element-caption\">m\u00e1quina de cortar cubos de cebola<\/figcaption><\/figure>    <p>Os par\u00e2metros acima da m\u00e1quina comercial de cortar cebola em cubos com pot\u00eancia de 1000kg \/ h. A partir desta lista de par\u00e2metros, voc\u00ea pode saber a pot\u00eancia, tens\u00e3o, peso e tamanho desta m\u00e1quina de processamento de cebola.<\/p>    <figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" src=\"https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/commercial-onion-dicer-machine.webp\" alt=\"m\u00e1quina comercial de cortar cebola\" class=\"wp-image-962\" srcset=\"https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/commercial-onion-dicer-machine.webp 720w, https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/commercial-onion-dicer-machine-480x360.webp 480w, https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/commercial-onion-dicer-machine-150x113.webp 150w, https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/commercial-onion-dicer-machine-16x12.webp 16w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">m\u00e1quina comercial de cortar cebola<\/figcaption><\/figure>    <h2 class=\"wp-block-heading\">Princ\u00edpio de funcionamento da m\u00e1quina comercial de cubos de cebola<\/h2>    <p>Quando a cebola \u00e9 alimentada na entrada da m\u00e1quina, o mostrador da m\u00e1quina comercial de cortar cebola far\u00e1 com que a cebola gire em alta velocidade. Sob a a\u00e7\u00e3o da for\u00e7a centr\u00edfuga, a faca vertical cortar\u00e1 a cebola em rodelas.<\/p>    <p>Em seguida, as rodelas de cebola passar\u00e3o pela faca de ralar para cortar as rodelas de cebola em tiras. Finalmente, a m\u00e1quina alimenta as tiras no cortador transversal, que as corta em cubos c\u00fabicos e retangulares.<\/p>    <p>O tamanho do produto acabado pode ser alterado ajustando a espessura das fatias e alterando o cortador rotativo e a faca transversal. Al\u00e9m disso, a espessura do corte pode ser ajustada na espessura desejada ajustando a placa de ajuste.<\/p>    <figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\"> <figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" data-id=\"969\" src=\"https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/vegetable-cubes.webp\" alt=\"cubos de vegetais\" class=\"wp-image-969\" srcset=\"https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/vegetable-cubes.webp 720w, https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/vegetable-cubes-480x360.webp 480w, https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/vegetable-cubes-150x113.webp 150w, https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/vegetable-cubes-16x12.webp 16w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">cubos de vegetais<\/figcaption><\/figure>    <figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" data-id=\"964\" src=\"https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/diced-onion.webp\" alt=\"cebola picada\" class=\"wp-image-964\" srcset=\"https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/diced-onion.webp 720w, https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/diced-onion-480x360.webp 480w, https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/diced-onion-150x113.webp 150w, https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/diced-onion-16x12.webp 16w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">cebola picada<\/figcaption><\/figure> <\/figure>    <h2 class=\"wp-block-heading\">Estrutura da m\u00e1quina autom\u00e1tica de corte de cebola em cubos<\/h2>    <p>A m\u00e1quina \u00e9 composta principalmente por uma base, mostrador, faca vertical, corpo de faca de seda, corpo de faca de corte transversal, sistema de transmiss\u00e3o e sistema de controle el\u00e9trico. A base da m\u00e1quina, a carca\u00e7a, a tremonha e as pe\u00e7as principais s\u00e3o feitas de a\u00e7o inoxid\u00e1vel. Isso garante que a m\u00e1quina autom\u00e1tica de corte de cebola em cubos n\u00e3o corroa, mesmo que funcione por muito tempo.<\/p>    <figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\"> <figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" data-id=\"967\" src=\"https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/machine-details-1.webp\" alt=\"detalhes da m\u00e1quina\" class=\"wp-image-967\" srcset=\"https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/machine-details-1.webp 720w, https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/machine-details-1-480x360.webp 480w, https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/machine-details-1-150x113.webp 150w, https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/machine-details-1-16x12.webp 16w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">detalhes da m\u00e1quina<\/figcaption><\/figure>    <figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" data-id=\"961\" src=\"https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/blades-of-the-machine.webp\" alt=\"l\u00e2minas da m\u00e1quina\" class=\"wp-image-961\" srcset=\"https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/blades-of-the-machine.webp 720w, https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/blades-of-the-machine-480x360.webp 480w, https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/blades-of-the-machine-150x113.webp 150w, https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/blades-of-the-machine-16x12.webp 16w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><figcaption class=\"wp-element-caption\">l\u00e2minas da m\u00e1quina<\/figcaption><\/figure> <\/figure>    <h2 class=\"wp-block-heading\">Como usar a m\u00e1quina de cubos de cebola Taizy?<\/h2>    <ol class=\"wp-block-list\"> <li>O material a ser cortado deve ser limpo primeiro.<\/li>    <li>Desligue a chave hk2-15, feche a porta do inv\u00f3lucro e pressione a chave de seguran\u00e7a XK. Quando a porta da carca\u00e7a n\u00e3o est\u00e1 fechada no lugar, o interruptor XK n\u00e3o pode ser pressionado e o motor n\u00e3o pode funcionar.<\/li>    <li>Ajuste a faca vertical, o cortador de disco e o cortador transversal para determinar o tamanho final.<\/li>    <li>Coloque o material na entrada do cortador de cebola.<\/li>    <li>Finalmente, ligue o interruptor.<\/li> <\/ol>    <figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-5 is-layout-flex wp-block-gallery-is-layout-flex\"> <figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"720\" data-id=\"960\" src=\"https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/automatic-onion-dicer-cutting-machine.webp\" alt=\"m\u00e1quina de corte autom\u00e1tica de cebola em cubos\" class=\"wp-image-960\" srcset=\"https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/automatic-onion-dicer-cutting-machine.webp 540w, https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/automatic-onion-dicer-cutting-machine-270x360.webp 270w, https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/automatic-onion-dicer-cutting-machine-9x12.webp 9w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><figcaption class=\"wp-element-caption\">m\u00e1quina de corte autom\u00e1tica de cebola em cubos<\/figcaption><\/figure>    <figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"720\" data-id=\"963\" src=\"https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/commercial-onion-dicing-machine.webp\" alt=\"m\u00e1quina comercial de cortar cebola em cubos\" class=\"wp-image-963\" srcset=\"https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/commercial-onion-dicing-machine.webp 540w, https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/commercial-onion-dicing-machine-270x360.webp 270w, https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/commercial-onion-dicing-machine-9x12.webp 9w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><figcaption class=\"wp-element-caption\">m\u00e1quina comercial de cortar cebola em cubos<\/figcaption><\/figure> <\/figure>    <h2 class=\"wp-block-heading\">Como escolher a m\u00e1quina cortadora de cebola certa para suas necessidades?<\/h2>    <p>Primeiro, voc\u00ea precisa determinar a sa\u00edda desejada.<\/p>    <p>Em segundo lugar, \u00e9 melhor voc\u00ea escolher a m\u00e1quina de cortar cebola que pode ajustar o tamanho do corte em cubos.<\/p>    <p>Tamb\u00e9m \u00e9 necess\u00e1rio escolher uma m\u00e1quina cortadora de cebola com uma ampla gama de aplica\u00e7\u00f5es.<\/p>    <p>Ent\u00e3o voc\u00ea precisa confirmar o material da m\u00e1quina. Seu n\u00famero de s\u00e9rie escolhe a m\u00e1quina cujo material \u00e9 a\u00e7o inoxid\u00e1vel 304.<\/p>    <p>Finalmente, voc\u00ea escolhe a m\u00e1quina cortadora de cebola que \u00e9 econ\u00f4mica.<\/p>","protected":false},"excerpt":{"rendered":"<p>A m\u00e1quina de cortar cebola Taizy pode cortar cebolas em cubos de 3 mm, 4 mm, 5 mm, 6 mm, 7 mm, 8 mm, 9 mm, 10 mm, 12 mm, 15 mm e 20 mm.<\/p>","protected":false},"author":1,"featured_media":965,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[1,7],"tags":[18],"class_list":["post-959","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-product","category-onion-machines","tag-onion"],"taxonomy_info":{"category":[{"value":1,"label":"Product"},{"value":7,"label":"Onion Machines"}],"post_tag":[{"value":18,"label":"onion"}]},"featured_image_src_large":["https:\/\/tzfoodmachine.com\/wp-content\/uploads\/2024\/05\/electric-onion-dicing-machine.webp",720,540,false],"author_info":{"display_name":"Judy Wang","author_link":"https:\/\/tzfoodmachine.com\/pt\/author\/adminjudy\/"},"comment_info":0,"category_info":[{"term_id":1,"name":"Product","slug":"product","term_group":0,"term_taxonomy_id":1,"taxonomy":"category","description":"","parent":0,"count":71,"filter":"raw","cat_ID":1,"category_count":71,"category_description":"","cat_name":"Product","category_nicename":"product","category_parent":0},{"term_id":7,"name":"Onion Machines","slug":"onion-machines","term_group":0,"term_taxonomy_id":7,"taxonomy":"category","description":"","parent":1,"count":12,"filter":"raw","cat_ID":7,"category_count":12,"category_description":"","cat_name":"Onion Machines","category_nicename":"onion-machines","category_parent":1}],"tag_info":[{"term_id":18,"name":"onion","slug":"onion","term_group":0,"term_taxonomy_id":18,"taxonomy":"post_tag","description":"","parent":0,"count":16,"filter":"raw"}],"_links":{"self":[{"href":"https:\/\/tzfoodmachine.com\/pt\/wp-json\/wp\/v2\/posts\/959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tzfoodmachine.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tzfoodmachine.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tzfoodmachine.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tzfoodmachine.com\/pt\/wp-json\/wp\/v2\/comments?post=959"}],"version-history":[{"count":0,"href":"https:\/\/tzfoodmachine.com\/pt\/wp-json\/wp\/v2\/posts\/959\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tzfoodmachine.com\/pt\/wp-json\/wp\/v2\/media\/965"}],"wp:attachment":[{"href":"https:\/\/tzfoodmachine.com\/pt\/wp-json\/wp\/v2\/media?parent=959"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tzfoodmachine.com\/pt\/wp-json\/wp\/v2\/categories?post=959"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tzfoodmachine.com\/pt\/wp-json\/wp\/v2\/tags?post=959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}